{"id":5763,"date":"2010-10-16T08:00:35","date_gmt":"2010-10-16T14:00:35","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=5763"},"modified":"2010-10-16T08:00:35","modified_gmt":"2010-10-16T14:00:35","slug":"la-necesidad-de-una-buena-educacion","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2010\/10\/16\/la-necesidad-de-una-buena-educacion\/","title":{"rendered":"La necesidad de una buena educaci\u00f3n"},"content":{"rendered":"<p>El sabio Licurgo que gobernaba en Esparta quiso demostrar al pueblo cu\u00e1n necesaria es la buena educaci\u00f3n a los ni\u00f1os.<\/p>\n<p>Para ello tom\u00f3 dos cachorros de perro de la misma camada y a uno le ense\u00f1\u00f3 a cazar, mientras que al otro le dej\u00f3 sin ense\u00f1ar nada. Cuando los perros hubieron crecido, congreg\u00f3 a los habitantes de la ciudad y les dijo:<\/p>\n<p>&#8211; O\u00eddme con atenci\u00f3n: La Patria necesita de ni\u00f1os y j\u00f3venes buenos, y para ello conseguir, es necesario que reciban buena y adecuada educaci\u00f3n.<\/p>\n<p>Mand\u00f3 traer a los dos perros, y mientras un hombre pon\u00eda ante ellos un plato de carne, otro soltaba una liebre. De inmediato, el uno se ech\u00f3 sobre el plato y el otro se lanz\u00f3 sobre la liebre. Licurgo dijo entonces:<\/p>\n<p>&#8211; Ved el resultado de la diferente educaci\u00f3n. Ambos animales nacieron juntos, empero se han educado de muy diferente manera, y el uno es un valiente cazador mientras que el otro es un glot\u00f3n despreciable. Si quer\u00e9is que vuestros hijos sean buenos, esforzados y valientes, obligadles a adquirir desde ni\u00f1os esas cualidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sabio Licurgo que gobernaba en Esparta quiso demostrar al pueblo cu\u00e1n necesaria es la buena educaci\u00f3n a los ni\u00f1os. Para ello tom\u00f3 dos cachorros de perro de la misma camada y a uno le ense\u00f1\u00f3 a cazar, mientras que al otro le dej\u00f3 sin ense\u00f1ar nada. Cuando los perros hubieron crecido, congreg\u00f3 a los &#8230; <a title=\"La necesidad de una buena educaci\u00f3n\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2010\/10\/16\/la-necesidad-de-una-buena-educacion\/\" aria-label=\"Leer m\u00e1s sobre La necesidad de una buena educaci\u00f3n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[28,18],"series":[],"class_list":["post-5763","post","type-post","status-publish","format-standard","hentry","category-limones","tag-animales","tag-hombre"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"PNNwyzHeRF\"><a href=\"https:\/\/quechilero.com\/blog\/2010\/10\/16\/la-necesidad-de-una-buena-educacion\/\">La necesidad de una buena educaci\u00f3n<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2010\/10\/16\/la-necesidad-de-una-buena-educacion\/embed\/#?secret=PNNwyzHeRF\" width=\"500\" height=\"350\" title=\"\u00abLa necesidad de una buena educaci\u00f3n\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"PNNwyzHeRF\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-1uX","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/5763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=5763"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/5763\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=5763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=5763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=5763"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=5763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}