{"id":5752,"date":"2010-10-10T08:00:17","date_gmt":"2010-10-10T14:00:17","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=5752"},"modified":"2010-10-10T08:00:17","modified_gmt":"2010-10-10T14:00:17","slug":"que-significa-amor-para-los-ninos-parte-ii","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2010\/10\/10\/que-significa-amor-para-los-ninos-parte-ii\/","title":{"rendered":"Qu\u00e9 significa \u00abamor\u00bb para los ni\u00f1os (Parte II)"},"content":{"rendered":"<p>Un grupo de profesionales le propuso a varios ni\u00f1os, con edades de 4 a 8 a\u00f1os, la pregunta <em>\u00ab\u00bfQu\u00e9 significa amor?\u00bb<\/em>, y las respuestas obtenidas fueron m\u00e1s amplias y profundas de lo que cualquiera pudo imaginar:<\/p>\n<p>&#8230;<\/p>\n<p><em>\u00abAmor es cuando mi mam\u00e1 hace caf\u00e9 para mi pap\u00e1 y ella prueba un poquito primero antes de d\u00e1rselo, para estar segura de que sabe bien.\u00bb<\/em><\/p>\n<p><em>\u00abAmor es cuando besas todo el tiempo, luego te cansas de besar, pero a\u00fan quieres estar junto a esa persona y entonces se hablan m\u00e1s.\u00bb<\/em><\/p>\n<p><em>\u00abAmor es lo que hay en el cuarto contigo en Navidad si dejas de abrir regalos y escuchas.\u00bb<\/em><\/p>\n<p><em>\u00abCuando le dices a alguien algo malo acerca de ti mismo y tienes miedo de que no te quieran m\u00e1s; pero te sorprendes de que no s\u00f3lo a\u00fan te aman, sino que te aman aun m\u00e1s.\u00bb<\/em><\/p>\n<p><em>\u00abAmor es cuando le dices a un muchacho que te gusta su camisa y \u00e9l la usa todos los d\u00edas.\u00bb<\/em><\/p>\n<p><em>\u00abAmor es como una viejita y un viejito que son amigos a\u00fan despu\u00e9s de conocerse muy, pero muy bien.\u00bb<\/em><\/p>\n<p><em>\u00abDurante mi primer recital, yo estaba en el escenario muy asustada, mir\u00e9 a toda la gente que me estaba viendo y vi a mi pap\u00e1 salud\u00e1ndome y sonri\u00e9ndome; \u00e9l era el \u00fanico haciendo eso y entonces ya no sent\u00ed miedo.\u00bb<\/em><\/p>\n<p><em>\u00abMi mam\u00e1 me ama m\u00e1s que nadie, nunca ver\u00e1s a nadie m\u00e1s besarme por las noches antes de irme a dormir.\u00bb<\/em><\/p>\n<p><em>\u00abAmor es cuando mami le da a papi el pedazo de pollo m\u00e1s grande.\u00bb<\/em><\/p>\n<p><em>\u00abAmor es cuando mami ve a papi sudoroso y oloroso y a\u00fan as\u00ed dice que es m\u00e1s guapo que Robert Redford.\u00bb<\/em><\/p>\n<p><em>\u00abAmor es cuando tu perrito te chupa la cara a\u00fan cuando lo has dejado todo el d\u00eda solo.\u00bb<\/em><\/p>\n<p><em>\u00abYo s\u00e9 que mi hermana mayor me ama porque ella me da toda su ropa que no usa y despu\u00e9s ella tiene que ir a comprar otra.\u00bb<\/em><\/p>\n<p>Uno no deber\u00eda decir <em>\u00abTe amo\u00bb<\/em> cuando en realidad no es as\u00ed&#8230; pero si realmente amas a alguien deber\u00edas dec\u00edrselo, puede ser que a esa persona se le haya olvidado.<\/p>\n<p>Comparte las sonrisas y la ternura que sentiste al leer \u00e9stas l\u00edneas&#8230; Puede que les ayude a reflexionar y recordar algunas cosas que quiz\u00e1 con el tiempo, ya est\u00e9n olvidando. Hay momentos en que perdemos al ni\u00f1o que fuimos, y dejamos de utilizar la imaginaci\u00f3n y nos volvemos torpes, pues dejamos escapar momentos que al final son los que m\u00e1s valen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de profesionales le propuso a varios ni\u00f1os, con edades de 4 a 8 a\u00f1os, la pregunta \u00ab\u00bfQu\u00e9 significa amor?\u00bb, y las respuestas obtenidas fueron m\u00e1s amplias y profundas de lo que cualquiera pudo imaginar: &#8230; \u00abAmor es cuando mi mam\u00e1 hace caf\u00e9 para mi pap\u00e1 y ella prueba un poquito primero antes de &#8230; <a title=\"Qu\u00e9 significa \u00abamor\u00bb para los ni\u00f1os (Parte II)\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2010\/10\/10\/que-significa-amor-para-los-ninos-parte-ii\/\" aria-label=\"Leer m\u00e1s sobre Qu\u00e9 significa \u00abamor\u00bb para los ni\u00f1os (Parte II)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[11,15,12,22,5,24],"series":[],"class_list":["post-5752","post","type-post","status-publish","format-standard","hentry","category-limones","tag-amigo","tag-amor","tag-cosas","tag-respuesta","tag-tiempo","tag-vida"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"BLl2GdBmva\"><a href=\"https:\/\/quechilero.com\/blog\/2010\/10\/10\/que-significa-amor-para-los-ninos-parte-ii\/\">Qu\u00e9 significa \u00abamor\u00bb para los ni\u00f1os (Parte II)<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2010\/10\/10\/que-significa-amor-para-los-ninos-parte-ii\/embed\/#?secret=BLl2GdBmva\" width=\"500\" height=\"350\" title=\"\u00abQu\u00e9 significa \u00abamor\u00bb para los ni\u00f1os (Parte II)\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"BLl2GdBmva\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-1uM","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/5752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=5752"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/5752\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=5752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=5752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=5752"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=5752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}