{"id":5256,"date":"2010-08-19T08:00:51","date_gmt":"2010-08-19T14:00:51","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=5256"},"modified":"2010-08-19T08:00:51","modified_gmt":"2010-08-19T14:00:51","slug":"maraton-de-blogs-mentes-kreativas-2","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2010\/08\/19\/maraton-de-blogs-mentes-kreativas-2\/","title":{"rendered":"Marat\u00f3n de Blogs: Mentes Kreativas"},"content":{"rendered":"<p><a href=\"http:\/\/s392.photobucket.com\/albums\/pp7\/pepejaguar\/maraton\/?action=view&amp;current=menteskreativas.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/maraton\/menteskreativas.png?resize=560%2C280\" alt=\"\" width=\"560\" height=\"280\" \/><\/a><\/p>\n<p>Fue en enero de 2009, cuando <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, de la mano de <em>Lesther Castillo<\/em>, inici\u00f3 sus publicaciones. <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/quechilero.com\/blog\/2009\/08\/09\/maraton-de-blogs-mentes-kreativas\/\">Anteriormente, <\/a><a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a> ya hab\u00eda participado de las actividades del <a title=\"Marat\u00f3n de Blogs 2010\" href=\"http:\/\/quechilero.com\/blog\/2010\/07\/31\/maraton-de-blogs-2010-listado\/\">Marat\u00f3n de Blogs<\/a>.<\/p>\n<p>Este es uno de los dos proyectos personales, en los que <em>Lesther<\/em> le imprime su sello muy personal y caracter\u00edstico. <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, est\u00e1 orientado principalmente, a los lectores interesados en <em>publicidad, comunicaci\u00f3n, tecnolog\u00eda y artes gr\u00e1ficas<\/em>.<\/p>\n<p>La actualizaci\u00f3n de Mentes Kreativa, es algo que preocupa a su autor y por eso le dedica el tiempo suficiente, para publicar contenido fresco, por lo que es posible encontrar siempre, art\u00edculos de inter\u00e9s, totalmente al d\u00eda, en muchas ocasiones, se actualiza casi al mismo tiempo en el que se realiza la actividad o se produce la noticia, lo que hace de <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, un buen referente para la b\u00fasqueda de informaci\u00f3n pertinente.<\/p>\n<p><!--more--><\/p>\n<p>Las galer\u00edas de fotos, es algo que siempre acompa\u00f1an a los art\u00edculos, como la buena cobertura del reciente <em>Festival de Antigua<\/em>. Es com\u00fan encontrar en <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, los comentarios de los lectores, puesto que los textos invitan, en muchos casos al debate y en otros a la reflexi\u00f3n, lo que mueve al grupo frecuente de lectores, a dejar su opini\u00f3n, con respecto del tema tratado.<\/p>\n<p>El dise\u00f1o del blog ha sufrido pocos cambios desde el a\u00f1o pasado, salvo algunos detalles, que incluyen la promoci\u00f3n de la participaci\u00f3n de <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, en las diferentes <em>redes sociales<\/em>.<\/p>\n<p>Art\u00edculos recientes que podemos encontrar en <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, son: <em>Pieza gr\u00e1fica para la Telet\u00f3n, Gustavo Ovalle portafolio creativo, Campa\u00f1a para ser mas puntual, Campa\u00f1a por el respeto a los dem\u00e1s, Amazon y su nuevo Kindle, aniversario de Caf\u00e9 Kreativo<\/em>, entre otros.<\/p>\n<p>De <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, me gusta mucho dos cosas: <em>la extensi\u00f3n de los art\u00edculos y las fotograf\u00edas<\/em>.<\/p>\n<p>Los art\u00edculos son extensos, pero no tanto que cansen la lectura, ni cortos que no cubran toda la informaci\u00f3n, tienen el justo tama\u00f1o, que motivan a la lectura. Esto se complementa perfectamente, con los <em>sets de fotos<\/em>, que siempre acompa\u00f1an a los art\u00edculos, muy buenas fotograf\u00edas, bien pensadas y muy bien tomadas.<\/p>\n<p>El recurso fotogr\u00e1fico, hace que el lector se transporte al lugar de la actividad, sintiendo que se estuvo en ese lugar tambi\u00e9n. Excelente complemento de los textos.<\/p>\n<p>B\u00e1sicamente la informaci\u00f3n, art\u00edculos y reportajes publicados en <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, se organizan en estas categor\u00edas, <em>art\u00edculos, entrevistas, eventos, feature, internet, noticias, publicidad, screen, social media, tecnolog\u00eda, twitter.<\/em><\/p>\n<p>Los invito a que lean <a title=\"Marat\u00f3n de Blogs 2010: Mentes Kreativas\" href=\"http:\/\/menteskreativas.com\/\" target=\"_blank\">Mentes Kreativas<\/a>, se suscriban por alguno de los medios a disposici\u00f3n y est\u00e9n pendientes de las actualizaciones constantes, con informaci\u00f3n de agencias de publicidad y medios creativos, principalmente de Guatemala.<\/p>\n<p>Ap\u00f3ya en:\u00a0<a class=\"plano\" title=\"Comp\u00e1rtelo en Twitter\" href=\"http:\/\/twitter.com\/home?status=Marat\u00f3n de Blogs 2010: Apoyando a Mentes Kreativas - http:\/\/bit.ly\/dyMS3a\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/quechilero.com\/blog\/wp-content\/themes\/crybook\/images\/twitter.png?resize=16%2C16\" alt=\"Twitter\" width=\"16\" height=\"16\" \/> Twitter<\/a> <a class=\"plano\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http:\/\/quechilero.com\/blog\/2010\/08\/19\/maraton-de-blogs-mentes-kreativas-2\/&amp;t=Marat\u00f3n de Blogs: Apoyando a Mentes Kreativas\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/quechilero.com\/blog\/wp-content\/themes\/crybook\/images\/facebook.png?resize=16%2C16\" alt=\"Facebook\" width=\"16\" height=\"16\" \/> Facebook<\/a> <a class=\"plano\" rel=\"bookmark\" href=\"http:\/\/www.google.com\/buzz\/post?url=http:\/\/quechilero.com\/blog\/2010\/08\/19\/maraton-de-blogs-mentes-kreativas-2\/&amp;imageurl=http:\/\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/maraton\/maraton468x602010.jpg&amp;type=normal-count\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/quechilero.com\/blog\/wp-content\/themes\/crybook\/images\/buzz.png?resize=16%2C16\" alt=\"Google Buzz\" width=\"16\" height=\"16\" \/> Google Buzz!<\/a><\/p>\n<p><a title=\"Marat\u00f3n de Blogs 2010\" href=\"http:\/\/quechilero.com\/blog\/2010\/07\/31\/maraton-de-blogs-2010-listado\/\">Lee aqu\u00ed, mas rese\u00f1as del Marat\u00f3n de Blogs 2010<\/a>.<\/p>\n<p><a title=\"Marat\u00f3n de Blogs 2010\" href=\"http:\/\/quechilero.com\/blog\/2010\/07\/31\/maraton-de-blogs-2010-listado\/\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/maraton\/maraton468x602010.jpg?resize=468%2C60\" alt=\"\" width=\"468\" height=\"60\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue en enero de 2009, cuando Mentes Kreativas, de la mano de Lesther Castillo, inici\u00f3 sus publicaciones. Anteriormente, Mentes Kreativas ya hab\u00eda participado de las actividades del Marat\u00f3n de Blogs. Este es uno de los dos proyectos personales, en los que Lesther le imprime su sello muy personal y caracter\u00edstico. Mentes Kreativas, est\u00e1 orientado principalmente, &#8230; <a title=\"Marat\u00f3n de Blogs: Mentes Kreativas\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2010\/08\/19\/maraton-de-blogs-mentes-kreativas-2\/\" aria-label=\"Leer m\u00e1s sobre Marat\u00f3n de Blogs: Mentes Kreativas\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[61],"tags":[4,12,51,7,8,10,27,81,62,43,55,5,24],"series":[],"class_list":["post-5256","post","type-post","status-publish","format-standard","hentry","category-blogs-de-guatemala","tag-blog","tag-cosas","tag-dios","tag-diseno","tag-fotografia","tag-guatemala","tag-internet","tag-lectura","tag-maraton","tag-proyecto","tag-tecnologia","tag-tiempo","tag-vida"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"pmuZxZUbKE\"><a href=\"https:\/\/quechilero.com\/blog\/2010\/08\/19\/maraton-de-blogs-mentes-kreativas-2\/\">Marat\u00f3n de Blogs: Mentes Kreativas<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2010\/08\/19\/maraton-de-blogs-mentes-kreativas-2\/embed\/#?secret=pmuZxZUbKE\" width=\"500\" height=\"350\" title=\"\u00abMarat\u00f3n de Blogs: Mentes Kreativas\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"pmuZxZUbKE\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-1mM","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/5256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=5256"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/5256\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=5256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=5256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=5256"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=5256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}