{"id":3878,"date":"2009-10-31T08:00:13","date_gmt":"2009-10-31T14:00:13","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=3878"},"modified":"2009-10-31T08:00:13","modified_gmt":"2009-10-31T14:00:13","slug":"halloween-y-los-ovnis-en-guatemala","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2009\/10\/31\/halloween-y-los-ovnis-en-guatemala\/","title":{"rendered":"Halloween y los Ovnis en Guatemala"},"content":{"rendered":"<p>Sin entrar a discutir <a title=\"Halloween y los Ovnis en Guatemala\" href=\"http:\/\/es.wikipedia.org\/wiki\/Halloween\" target=\"_blank\">sobre los or\u00edgenes del <strong>Hallowen<\/strong><\/a>, aprovechando el d\u00eda y que como muchas otros <em>d\u00edas festivos<\/em>, este tambi\u00e9n ha sido absorbido por el <em>consumismo que devora <\/em>todo lo que encuentra a su paso. A estas alturas, ya dej\u00f3 de ser lo que en un momento fue, perdi\u00f3 su objetivo inicial y ha sido <em>consumido<\/em> por la fabulosa maquinaria publicitaria, que lo ha convertido en una <em>excusa mas<\/em> para <em>tener que comprar algo<\/em> que no necesitamos, y a gastar el dinero que no tenemos, al menos para muchos es as\u00ed.<\/p>\n<p>Pues aprovechando la simbolog\u00eda del d\u00eda, y mezclando el asunto del <em>d\u00eda de brujas<\/em> con el <em>fen\u00f3meno ovni<\/em>, en este texto, pretendo hacer una peque\u00f1a rese\u00f1a de lo que aqu\u00ed tambi\u00e9n se <em>hace, habla y produce<\/em> al respecto.<\/p>\n<p><strong>Ovni en Tikal Futura<\/strong><\/p>\n<p>Como siempre el humor <em>guatemalteco<\/em>, siempre presente en todo momento, vemos este video de un <em>platillo volador sobre Tikal Futura<\/em>, \u00bfcampa\u00f1a publicitaria, ejercicio de la universidad o simple comicidad?<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"550\" height=\"344\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/eqAK1CgFCk4&amp;hl=es&amp;fs=1&amp;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><\/p>\n<p><!--more--><\/p>\n<p><strong>Ovni en el Volc\u00e1n Santiaguito<\/strong><\/p>\n<p>Estas fotograf\u00edas y video, fueron tomados por unos <em>periodistas<\/em> y aparentemente, no se hab\u00edan dado cuenta, solo hasta que revisaron el material que hab\u00edan tomado. \u00bfSer\u00e1 que este <em>noticiero y sus periodistas<\/em> necesitan subir sus n\u00fameros de rating, o ser\u00e1 posible que un <em>objeto extraterrestre<\/em>, estuviera en el\u00a0 <em>momento exacto<\/em>?<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"550\" height=\"344\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/YuXMApQZGS4&amp;color1=0xb1b1b1&amp;color2=0xcfcfcf&amp;hl=es&amp;feature=player_embedded&amp;fs=1\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><\/p>\n<p><strong>Ovni en el Aeropuerto Internacional La Aurora<\/strong><\/p>\n<p>Este otro video, fue <em>supuestamente<\/em> grabado por otro <em>reportero<\/em> de un programa de televisi\u00f3n que pasan en la televisi\u00f3n abierta, en el horario nocturno. Que dif\u00edcil de creer en la veracidad del video, al menos los del video de <em>Tikal Futura<\/em>, le pusieron un poco de <em>humor y efectos especiales<\/em>, adem\u00e1s de estar mucho mejor preparado.<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"550\" height=\"344\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/QNpKIAESndo&amp;hl=es&amp;fs=1&amp;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><\/p>\n<p><strong>Ovni sobrevolando la Zona 4 de la capital de Guatemala<\/strong><\/p>\n<p>Otro video <em>casero<\/em>, aunque talvez es el mejor de todos, que muestra un objeto <em>blanco<\/em>, sobrevolar de forma <em>err\u00e1tica y sin un patr\u00f3n establecido<\/em>, sobre algunos edificios de la Zona 4 en Ciudad de Guatemala, el lugar es f\u00e1cilmente identificable y lo que falta por saber es \u00bfque es ese objeto blanco?<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"550\" height=\"344\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/7060iXsr7Ck&amp;hl=es&amp;fs=1&amp;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><\/p>\n<p>Si alguien est\u00e1 interesado en seguir viendo <a title=\"Halloween y los Ovnis en Guatemala\" href=\"http:\/\/video.google.com.gt\/videosearch?hl=es&amp;source=hp&amp;q=ovnis+en+guatemala&amp;um=1&amp;ie=UTF-8&amp;ei=6VzeSpyxPMLP8QbP38Rq&amp;sa=X&amp;oi=video_result_group&amp;ct=title&amp;resnum=8&amp;ved=0CCMQqwQwBw#\" target=\"_blank\">videos de <strong>Ovnis en Guatemala<\/strong><\/a>, puede seguir el enlace.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin entrar a discutir sobre los or\u00edgenes del Hallowen, aprovechando el d\u00eda y que como muchas otros d\u00edas festivos, este tambi\u00e9n ha sido absorbido por el consumismo que devora todo lo que encuentra a su paso. A estas alturas, ya dej\u00f3 de ser lo que en un momento fue, perdi\u00f3 su objetivo inicial y ha &#8230; <a title=\"Halloween y los Ovnis en Guatemala\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2009\/10\/31\/halloween-y-los-ovnis-en-guatemala\/\" aria-label=\"Leer m\u00e1s sobre Halloween y los Ovnis en Guatemala\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[26,32,8,10,25,53],"series":[],"class_list":["post-3878","post","type-post","status-publish","format-standard","hentry","category-limones","tag-dinero","tag-especial","tag-fotografia","tag-guatemala","tag-video","tag-youtube"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"YX0ia2uU3G\"><a href=\"https:\/\/quechilero.com\/blog\/2009\/10\/31\/halloween-y-los-ovnis-en-guatemala\/\">Halloween y los Ovnis en Guatemala<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2009\/10\/31\/halloween-y-los-ovnis-en-guatemala\/embed\/#?secret=YX0ia2uU3G\" width=\"500\" height=\"350\" title=\"\u00abHalloween y los Ovnis en Guatemala\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"YX0ia2uU3G\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/pDKli-10y","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5937,"url":"https:\/\/quechilero.com\/blog\/2010\/10\/31\/disfraces-sexy-para-halloween\/","url_meta":{"origin":3878,"position":0},"title":"Disfraces sexy para Halloween","author":"Pepe Barrascout Ortiz","date":"31 octubre 2010","format":false,"excerpt":"Hoy muchas personas, con la excusa perfecta de Halloween lo aprovechan para salir de fiesta y en busca de un buen disfraz para este d\u00eda, ac\u00e1 hay una selecci\u00f3n de algunos muy sexys y poco comunes, disfraces sexys de Halloween para chicas. Estos dise\u00f1os de disfraces son provocadores y sugerentes,\u2026","rel":"","context":"En \u00abLimones\u00bb","block_context":{"text":"Limones","link":"https:\/\/quechilero.com\/blog\/category\/limones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/blog\/disfraces-halloween-1.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/blog\/disfraces-halloween-1.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/blog\/disfraces-halloween-1.png?resize=525%2C300 1.5x"},"classes":[]},{"id":9546,"url":"https:\/\/quechilero.com\/blog\/2011\/06\/25\/dia-del-maestro\/","url_meta":{"origin":3878,"position":1},"title":"D\u00eda del Maestro","author":"Pepe Barrascout Ortiz","date":"25 junio 2011","format":false,"excerpt":"Como un homenaje a mis colegas maestros, comparto estos art\u00edculos, que a lo largo de cinco a\u00f1os, he publicado en Si la vida nos da limones..., pero solo a aquellos que con \u00e1nimo y energ\u00eda, vocaci\u00f3n y entrega, d\u00eda a d\u00eda, asisten puntuales a la cita que tienen con la\u2026","rel":"","context":"En \u00abLimones\u00bb","block_context":{"text":"Limones","link":"https:\/\/quechilero.com\/blog\/category\/limones\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10906,"url":"https:\/\/quechilero.com\/blog\/2011\/10\/29\/en-halloween-maquillate-como-katy-perry\/","url_meta":{"origin":3878,"position":2},"title":"En Halloween: maqu\u00edllate como Katy Perry","author":"Pepe Barrascout Ortiz","date":"29 octubre 2011","format":false,"excerpt":"Un breve pero muy completo tutorial, para que te puedas maquillar al estilo de Katy Perry\u00a0y aprovechar para lucir en la parranda de halloween\u00a0de este a\u00f1o. Presta atenci\u00f3n a los detalles y maqu\u00edllate como las estrellas famosas. https:\/\/youtu.be\/mbjIZNtC8OY","rel":"","context":"En \u00abLimones\u00bb","block_context":{"text":"Limones","link":"https:\/\/quechilero.com\/blog\/category\/limones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/mbjIZNtC8OY\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":19229,"url":"https:\/\/quechilero.com\/blog\/2014\/08\/16\/gracias-mis-amigos\/","url_meta":{"origin":3878,"position":3},"title":"Gracias mis amigos","author":"Pepe Barrascout Ortiz","date":"16 agosto 2014","format":false,"excerpt":"Gracias mis amigos, a todos y cada uno de ustedes que me han manifestado sus muestras de aprecio y cari\u00f1o de las mas distintas formas, con las mas diferentes tecnolog\u00edas y con los estilos propios de cada uno, les agradezco profundamente el tiempo y la molestia que se tomaron, en\u2026","rel":"","context":"En \u00abLimones\u00bb","block_context":{"text":"Limones","link":"https:\/\/quechilero.com\/blog\/category\/limones\/"},"img":{"alt_text":"Gracias mis amigos","src":"https:\/\/i0.wp.com\/lh5.googleusercontent.com\/-RpS6pfoWehM\/U-6vWpl4kKI\/AAAAAAAADLY\/NacLjVERaX0\/s800\/cumplea%2525C3%2525B1os2014-01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lh5.googleusercontent.com\/-RpS6pfoWehM\/U-6vWpl4kKI\/AAAAAAAADLY\/NacLjVERaX0\/s800\/cumplea%2525C3%2525B1os2014-01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lh5.googleusercontent.com\/-RpS6pfoWehM\/U-6vWpl4kKI\/AAAAAAAADLY\/NacLjVERaX0\/s800\/cumplea%2525C3%2525B1os2014-01.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3263,"url":"https:\/\/quechilero.com\/blog\/2009\/08\/21\/maraton-de-blogs-blog-guatemala\/","url_meta":{"origin":3878,"position":4},"title":"Marat\u00f3n de Blogs: Blog Guatemala","author":"Pepe Barrascout Ortiz","date":"21 agosto 2009","format":false,"excerpt":"Con mas de 3 a\u00f1os de actividad (febrero 2006) y de la mano de Hugo M\u00e9ndez, Blog Guatemala se ha dedicado a presentar el lado bonito de nuestro pa\u00eds, los temas de inter\u00e9s no se hacen esperar y d\u00eda a d\u00eda, son muchos los art\u00edculos de fondo que podemos leer\u2026","rel":"","context":"En \u00abBlogs de Guatemala\u00bb","block_context":{"text":"Blogs de Guatemala","link":"https:\/\/quechilero.com\/blog\/category\/blogs-de-guatemala\/"},"img":{"alt_text":"Marat\u00f3n de Blogs 2009","src":"https:\/\/i0.wp.com\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/maraton2009\/maraton2009.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/maraton2009\/maraton2009.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/i392.photobucket.com\/albums\/pp7\/pepejaguar\/maraton2009\/maraton2009.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":8604,"url":"https:\/\/quechilero.com\/blog\/2011\/04\/23\/dia-de-la-tierra-y-contaminacion\/","url_meta":{"origin":3878,"position":5},"title":"D\u00eda de la Tierra y Contaminaci\u00f3n","author":"Pepe Barrascout Ortiz","date":"23 abril 2011","format":false,"excerpt":"El 22 de abril, se celebra, el D\u00eda de la Tierra, que tiene entre otras cosas, tiene el fin de hacer conciencia sobre el uso adecuado de los recursos y de la importancia de mantener y conservar el ambiente. En muchos pa\u00edses, sino es que en todos, hay instituciones encargadas\u2026","rel":"","context":"En \u00abLimones\u00bb","block_context":{"text":"Limones","link":"https:\/\/quechilero.com\/blog\/category\/limones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/ocu4lp8fZAE\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/3878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=3878"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/3878\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=3878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=3878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=3878"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=3878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}