{"id":2883,"date":"2009-07-13T08:00:27","date_gmt":"2009-07-13T14:00:27","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=2883"},"modified":"2009-07-13T08:00:27","modified_gmt":"2009-07-13T14:00:27","slug":"video-stop-motion-post-its","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2009\/07\/13\/video-stop-motion-post-its\/","title":{"rendered":"Video Stop Motion + Post-its"},"content":{"rendered":"<p>Siempre me han gustado los videos y producciones en los que interviene el <em>\u00abstop motion\u00bb<\/em>, quiz\u00e1 por la fascinaci\u00f3n que tambi\u00e9n he tenido por aquellas <em>largas serpientes<\/em> que se formaban con fichas de domin\u00f3, y que despu\u00e9s de muchas horas de trabajo, eran tiradas gracias a una reacci\u00f3n en cadena.<\/p>\n<p>Este video fue creado por Bang-yao Liu, en el que utiliz\u00f3 un poco mas de <strong>6,000 post-its<\/strong>, aquellos famosos <em>papelitos amarillos<\/em>, con pegamento en la parte posterior y que normalmente son utilizados para anotar asuntos pendientes.<\/p>\n<p>Pues <em>Liu<\/em>, utiliz\u00f3 esta enorme cantidad de ellos, mas <em>3 meses de planeaci\u00f3n<\/em> y preparaci\u00f3n, para conclu\u00edr con <em>4 d\u00edas de grabaci\u00f3n<\/em>, junto a algunos amigos que lo ayudaron en su tarea.<\/p>\n<p>Esta producci\u00f3n forma parte de su proyecto final de carrera.<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"550\" height=\"344\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/BpWM0FNPZSs&amp;color1=0xb1b1b1&amp;color2=0xcfcfcf&amp;hl=es&amp;feature=player_embedded&amp;fs=1\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><\/p>\n<p>Lo que siempre me ha gustado de este tipo de producciones, tanto <em>el stop motion como las serpientes de fichas de domin\u00f3<\/em>, es la gran paciencia que deben tener sus autores, lo que indiscutiblemente es una gran virtud, digna de imitar.<\/p>\n<p>El video lo vi en <a title=\"Video Stop Motion + Post-its\" href=\"http:\/\/www.ateneupopular.com\/\" target=\"_blank\"><em>Ateneupopular<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siempre me han gustado los videos y producciones en los que interviene el \u00abstop motion\u00bb, quiz\u00e1 por la fascinaci\u00f3n que tambi\u00e9n he tenido por aquellas largas serpientes que se formaban con fichas de domin\u00f3, y que despu\u00e9s de muchas horas de trabajo, eran tiradas gracias a una reacci\u00f3n en cadena. Este video fue creado por &#8230; <a title=\"Video Stop Motion + Post-its\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2009\/07\/13\/video-stop-motion-post-its\/\" aria-label=\"Leer m\u00e1s sobre Video Stop Motion + Post-its\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[14,11,37,60,43,36,25,53],"series":[],"class_list":["post-2883","post","type-post","status-publish","format-standard","hentry","category-limones","tag-accion","tag-amigo","tag-ayuda","tag-paciencia","tag-proyecto","tag-trabajo","tag-video","tag-youtube"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"Hi9VGT8WKb\"><a href=\"https:\/\/quechilero.com\/blog\/2009\/07\/13\/video-stop-motion-post-its\/\">Video Stop Motion + Post-its<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2009\/07\/13\/video-stop-motion-post-its\/embed\/#?secret=Hi9VGT8WKb\" width=\"500\" height=\"350\" title=\"\u00abVideo Stop Motion + Post-its\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"Hi9VGT8WKb\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-Kv","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/2883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=2883"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/2883\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=2883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=2883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=2883"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=2883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}