{"id":27454,"date":"2010-10-16T06:00:46","date_gmt":"2010-10-16T12:00:46","guid":{"rendered":"https:\/\/quechilero.com\/blog\/?post_type=podcast&#038;p=27454"},"modified":"2018-08-17T18:39:19","modified_gmt":"2018-08-18T00:39:19","slug":"podcast-las-6-de-la-manana-episodio-03","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2010\/10\/16\/podcast-las-6-de-la-manana-episodio-03\/","title":{"rendered":"Podcast: Las 6 de la ma\u00f1ana, episodio 03"},"content":{"rendered":"<p>Bienvenidos al tercer episodio de\u00a0<strong>\u201cLas \u00a06 de la ma\u00f1ana\u201d<\/strong>, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo.<\/p>\n<p>El listado para hoy es:<\/p>\n<p><em><em>Artista<\/em> \/ Tema<\/em><br \/>\n01 &#8211; Leonard Zelig &#8211; Doble Riesgo<br \/>\n02 &#8211; Chris Skinner &#8211; Cats Eyes<br \/>\n03 &#8211; Christopher Squier &#8211; When Heroes Hide<br \/>\n04 &#8211; Marwood Williams &#8211; In the Parking Lot<br \/>\n05 &#8211; Moptzar &#8211; 03 Rita Joe<br \/>\n06 &#8211; Plagio &#8211; Not enough<\/p>\n<p>A iniciar el d\u00eda con \u00e1nimo y positivismo.<\/p>\n<p><a title=\"Podcast Las Seis de la Ma\u00f1ana\" href=\"http:\/\/feeds.feedburner.com\/silavidanosdalimonespodcast\" target=\"_blank\" rel=\"noopener\">Suscribirte para descargar este y otros episodios<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenidos al tercer episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 &#8211; Leonard Zelig &#8211; Doble Riesgo 02 &#8211; Chris Skinner &#8211; Cats Eyes 03 &#8211; Christopher Squier &#8211; When Heroes &#8230; <a title=\"Podcast: Las 6 de la ma\u00f1ana, episodio 03\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2010\/10\/16\/podcast-las-6-de-la-manana-episodio-03\/\" aria-label=\"Leer m\u00e1s sobre Podcast: Las 6 de la ma\u00f1ana, episodio 03\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":22662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"audio","audio_file":"http:\/\/media.blubrry.com\/quechilero\/dts.podtrac.com\/redirect.mp3\/archive.org\/download\/Las6Am\/6am-podcast-03.mp3","cover_image":"","cover_image_id":"","duration":"26:19","filesize":"24.1M","date_recorded":"","explicit":"","block":"","filesize_raw":"25269185","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[120,111],"tags":[112,70,51,68,101],"series":[130],"class_list":["post-27454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-las-6-de-la-manana","category-podcast","tag-animo","tag-descarga","tag-dios","tag-mp3","tag-podcast-2","series-las-6am"],"episode_featured_image":"https:\/\/quechilero.com\/blog\/imagenes\/las6am.jpg","episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"https:\/\/op3.dev\/e,pg=d4a7cbf0-0244-5cca-b5f7-502b9b5a3298\/quechilero.com\/blog\/podcast-download\/27454\/podcast-las-6-de-la-manana-episodio-03.mp3","player_link":"https:\/\/op3.dev\/e,pg=d4a7cbf0-0244-5cca-b5f7-502b9b5a3298\/quechilero.com\/blog\/podcast-player\/27454\/podcast-las-6-de-la-manana-episodio-03.mp3","audio_player":null,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/itunes.apple.com\/gt\/podcast\/las-6-la-ma\u00f1ana\/id1093638748","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"https:\/\/castbox.fm\/channel\/Las-6-de-la-ma%C3%B1ana-id1398755?country=gt","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"https:\/\/podcasts.google.com\/feed\/aHR0cDovL2ZlZWQucXVlY2hpbGVyby5jb20vbGFzNmFt","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"http:\/\/feed.quechilero.com\/las6am","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"https:\/\/www.stitcher.com\/podcast\/pepe-barrascout\/las-6-de-la-maana","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"https:\/\/mx.ivoox.com\/es\/podcast-6-manana_sq_f19907_1.html","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/las-6am","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"K03Fjym9Wn\"><a href=\"https:\/\/quechilero.com\/blog\/2010\/10\/16\/podcast-las-6-de-la-manana-episodio-03\/\">Podcast: Las 6 de la ma\u00f1ana, episodio 03<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2010\/10\/16\/podcast-las-6-de-la-manana-episodio-03\/embed\/#?secret=K03Fjym9Wn\" width=\"500\" height=\"350\" title=\"\u00abPodcast: Las 6 de la ma\u00f1ana, episodio 03\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"K03Fjym9Wn\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pDKli-78O","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/27454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=27454"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/27454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media\/22662"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=27454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=27454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=27454"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=27454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}