{"id":24355,"date":"2011-09-18T06:00:16","date_gmt":"2011-09-18T12:00:16","guid":{"rendered":"https:\/\/quechilero.com\/blog\/?post_type=podcast&#038;p=24355"},"modified":"2019-08-23T13:06:37","modified_gmt":"2019-08-23T19:06:37","slug":"podcast-las-6-de-la-manana-episodio-340","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2011\/09\/18\/podcast-las-6-de-la-manana-episodio-340\/","title":{"rendered":"Podcast: Las 6 de la ma\u00f1ana, episodio 340"},"content":{"rendered":"<p>Bienvenidos al tricent\u00e9simo cuadrag\u00e9simo episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo.<\/p>\n<p>El listado para hoy es:<\/p>\n<p>Artista \/ Tema<\/p>\n<p>01 &#8211; Gaby Cardoso &#8211; DESPUES DE LAS IMAGENES<br \/>\n02 &#8211; AXIAL &#8211; Feitico Infinito<br \/>\n03 &#8211; Psy Brazil &#8211; Electric Funky &#8211; I&#8217;m So Young<br \/>\n04 &#8211; Lorenzo&#8217;s Music &#8211; Someday<br \/>\n05 &#8211; Lorenzo&#8217;s Music &#8211; One Time<br \/>\n06 &#8211; MMO &#8211; Piranhas<\/p>\n<p>A iniciar el d\u00eda con energ\u00eda, \u00e1nimo y positivismo.<\/p>\n<p><a title=\"Podcast Las Seis de la Ma\u00f1ana\" href=\"http:\/\/quechilero.com\/blog\/category\/podcast\/\" target=\"_blank\" rel=\"noopener noreferrer\">Descarga este y otros episodios<\/a>.<\/p>\n<p><a title=\"Podcast Las 6 de la Ma\u00f1ana\" href=\"http:\/\/feeds.feedburner.com\/las6am\" rel=\"alternate\" type=\"application\/rss+xml\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Podcast Las 6 de la Ma\u00f1ana\" src=\"https:\/\/i0.wp.com\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png?w=1200&#038;ssl=1\" alt=\"\" \/><\/a> <a href=\"http:\/\/feeds.feedburner.com\/las6am\" rel=\"alternate\" type=\"application\/rss+xml\">Suscr\u00edbete al podcast<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenidos al tricent\u00e9simo cuadrag\u00e9simo episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 &#8211; Gaby Cardoso &#8211; DESPUES DE LAS IMAGENES 02 &#8211; AXIAL &#8211; Feitico Infinito 03 &#8211; Psy Brazil &#8211; &#8230; <a title=\"Podcast: Las 6 de la ma\u00f1ana, episodio 340\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2011\/09\/18\/podcast-las-6-de-la-manana-episodio-340\/\" aria-label=\"Leer m\u00e1s sobre Podcast: Las 6 de la ma\u00f1ana, episodio 340\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":22662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","episode_type":"audio","audio_file":"http:\/\/media.blubrry.com\/quechilero\/dts.podtrac.com\/redirect.mp3\/archive.org\/download\/Las6Am\/6am-podcast-340.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"24:38","filesize":"22.41M","filesize_raw":"23502488","date_recorded":"","explicit":"","block":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[120,111],"tags":[112,70,51,71,101],"series":[130],"class_list":["post-24355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-las-6-de-la-manana","category-podcast","tag-animo","tag-descarga","tag-dios","tag-energia","tag-podcast-2","series-las-6am"],"episode_featured_image":"https:\/\/quechilero.com\/blog\/imagenes\/las6am.jpg","episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"https:\/\/op3.dev\/e,pg=d4a7cbf0-0244-5cca-b5f7-502b9b5a3298\/quechilero.com\/blog\/podcast-download\/24355\/podcast-las-6-de-la-manana-episodio-340.mp3","player_link":"https:\/\/op3.dev\/e,pg=d4a7cbf0-0244-5cca-b5f7-502b9b5a3298\/quechilero.com\/blog\/podcast-player\/24355\/podcast-las-6-de-la-manana-episodio-340.mp3","audio_player":null,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/itunes.apple.com\/gt\/podcast\/las-6-la-ma\u00f1ana\/id1093638748","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"https:\/\/castbox.fm\/channel\/Las-6-de-la-ma%C3%B1ana-id1398755?country=gt","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"https:\/\/podcasts.google.com\/feed\/aHR0cDovL2ZlZWQucXVlY2hpbGVyby5jb20vbGFzNmFt","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"http:\/\/feed.quechilero.com\/las6am","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"https:\/\/www.stitcher.com\/podcast\/pepe-barrascout\/las-6-de-la-maana","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"https:\/\/mx.ivoox.com\/es\/podcast-6-manana_sq_f19907_1.html","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/las-6am","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"BrKzp2TAMU\"><a href=\"https:\/\/quechilero.com\/blog\/2011\/09\/18\/podcast-las-6-de-la-manana-episodio-340\/\">Podcast: Las 6 de la ma\u00f1ana, episodio 340<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2011\/09\/18\/podcast-las-6-de-la-manana-episodio-340\/embed\/#?secret=BrKzp2TAMU\" width=\"500\" height=\"350\" title=\"\u00abPodcast: Las 6 de la ma\u00f1ana, episodio 340\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"BrKzp2TAMU\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/pDKli-6kP","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":23847,"url":"https:\/\/quechilero.com\/blog\/2013\/02\/06\/podcast-las-6-de-la-manana-episodio-847\/","url_meta":{"origin":24355,"position":0},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 847","author":"Pepe Barrascout Ortiz","date":"6 febrero 2013","format":false,"excerpt":"Bienvenidos al octingent\u00e9simo cuadrag\u00e9simo s\u00e9ptimo episodio de \u201cLas 6 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Lorenzo's Music - Down the stairway 02 - Lorenzo's Music -\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":23848,"url":"https:\/\/quechilero.com\/blog\/2013\/02\/05\/podcast-las-6-de-la-manana-episodio-846\/","url_meta":{"origin":24355,"position":1},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 846","author":"Pepe Barrascout Ortiz","date":"5 febrero 2013","format":false,"excerpt":"Bienvenidos al octingent\u00e9simo cuadrag\u00e9simo sexto episodio de \u201cLas 6 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Lorenzo's Music - You got to feel it tonight 02 -\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":23846,"url":"https:\/\/quechilero.com\/blog\/2013\/02\/07\/podcast-las-6-de-la-manana-episodio-848\/","url_meta":{"origin":24355,"position":2},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 848","author":"Pepe Barrascout Ortiz","date":"7 febrero 2013","format":false,"excerpt":"Bienvenidos al octingent\u00e9simo cuadrag\u00e9simo octavo episodio de \u201cLas 6 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Paper Plane Pilots - Winter in the sun 02 - Paper\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":24356,"url":"https:\/\/quechilero.com\/blog\/2011\/09\/17\/podcast-las-6-de-la-manana-episodio-339\/","url_meta":{"origin":24355,"position":3},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 339","author":"Pepe Barrascout Ortiz","date":"17 septiembre 2011","format":false,"excerpt":"Bienvenidos al tricent\u00e9simo trig\u00e9simo noveno episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Gaby Cardoso - RIO INDIVIDUAL 02 - AXIAL - Senoide 03 -\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":24339,"url":"https:\/\/quechilero.com\/blog\/2011\/10\/04\/podcast-las-6-de-la-manana-episodio-356\/","url_meta":{"origin":24355,"position":4},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 356","author":"Pepe Barrascout Ortiz","date":"4 octubre 2011","format":false,"excerpt":"Bienvenidos al tricent\u00e9simo quincuag\u00e9simo sexto episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Josh Woodward - Once Tomorrow 02 - Roger Subirana Mata - Shedneryan\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":24357,"url":"https:\/\/quechilero.com\/blog\/2011\/09\/16\/podcast-las-6-de-la-manana-episodio-338\/","url_meta":{"origin":24355,"position":5},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 338","author":"Pepe Barrascout Ortiz","date":"16 septiembre 2011","format":false,"excerpt":"Bienvenidos al tricent\u00e9simo trig\u00e9simo octavo episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Josh Woodward - I'm Not Dreaming 02 - Maya Filipic - Stories\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1","_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/24355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=24355"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/24355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media\/22662"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=24355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=24355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=24355"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=24355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}