{"id":23840,"date":"2013-02-13T06:00:01","date_gmt":"2013-02-13T12:00:01","guid":{"rendered":"https:\/\/quechilero.com\/blog\/?post_type=podcast&#038;p=23840"},"modified":"2019-09-03T19:11:35","modified_gmt":"2019-09-04T01:11:35","slug":"podcast-las-6-de-la-manana-episodio-854","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2013\/02\/13\/podcast-las-6-de-la-manana-episodio-854\/","title":{"rendered":"Podcast: Las 6 de la ma\u00f1ana, episodio 854"},"content":{"rendered":"<p>Bienvenidos al octingent\u00e9simo quincuag\u00e9simo cuarto episodio de \u201cLas 6 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo.<\/p>\n<p>El listado para hoy es:<\/p>\n<p>Artista \/ Tema<\/p>\n<p>01 &#8211; Stormy Mondays &#8211; Same old song<br \/>\n02 &#8211; Stormy Mondays &#8211; Folk Lullaby<br \/>\n03 &#8211; Stormy Mondays &#8211; Whenever I fall<br \/>\n04 &#8211; Stormy Mondays &#8211; Here she comes<br \/>\n05 &#8211; Stormy Mondays &#8211; Nothing on my radio<br \/>\n06 &#8211; Stormy Mondays &#8211; On the run<\/p>\n<p>A iniciar el d\u00eda con energ\u00eda, \u00e1nimo y positivismo.<\/p>\n<p><a title=\"Podcast Las Seis de la Ma\u00f1ana\" href=\"http:\/\/quechilero.com\/blog\/category\/podcast\/\" target=\"_blank\" rel=\"noopener noreferrer\">Descarga este y otros episodios<\/a>.<\/p>\n<p><a title=\"Podcast Las 6 de la Ma\u00f1ana\" href=\"http:\/\/feeds.feedburner.com\/las6am\" rel=\"alternate\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Podcast Las 6 de la Ma\u00f1ana\" src=\"https:\/\/i0.wp.com\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png?w=1200&#038;ssl=1\" alt=\"\" \/><\/a>\u00a0<a href=\"http:\/\/feeds.feedburner.com\/las6am\" rel=\"alternate\">Suscr\u00edbete al podcast<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenidos al octingent\u00e9simo quincuag\u00e9simo cuarto episodio de \u201cLas 6 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 &#8211; Stormy Mondays &#8211; Same old song 02 &#8211; Stormy Mondays &#8211; Folk Lullaby 03 &#8211; Stormy &#8230; <a title=\"Podcast: Las 6 de la ma\u00f1ana, episodio 854\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2013\/02\/13\/podcast-las-6-de-la-manana-episodio-854\/\" aria-label=\"Leer m\u00e1s sobre Podcast: Las 6 de la ma\u00f1ana, episodio 854\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":22662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","episode_type":"audio","audio_file":"http:\/\/media.blubrry.com\/quechilero\/dts.podtrac.com\/redirect.mp3\/archive.org\/download\/Las6Am\/6am-podcast-854.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"21:14","filesize":"19.45M","filesize_raw":"20395798","date_recorded":"","explicit":"","block":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[120,111],"tags":[112,70,51,71,101],"series":[130],"class_list":["post-23840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-las-6-de-la-manana","category-podcast","tag-animo","tag-descarga","tag-dios","tag-energia","tag-podcast-2","series-las-6am"],"episode_featured_image":"https:\/\/quechilero.com\/blog\/imagenes\/las6am.jpg","episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"https:\/\/op3.dev\/e,pg=d4a7cbf0-0244-5cca-b5f7-502b9b5a3298\/quechilero.com\/blog\/podcast-download\/23840\/podcast-las-6-de-la-manana-episodio-854.mp3","player_link":"https:\/\/op3.dev\/e,pg=d4a7cbf0-0244-5cca-b5f7-502b9b5a3298\/quechilero.com\/blog\/podcast-player\/23840\/podcast-las-6-de-la-manana-episodio-854.mp3","audio_player":null,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/itunes.apple.com\/gt\/podcast\/las-6-la-ma\u00f1ana\/id1093638748","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"https:\/\/castbox.fm\/channel\/Las-6-de-la-ma%C3%B1ana-id1398755?country=gt","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"https:\/\/podcasts.google.com\/feed\/aHR0cDovL2ZlZWQucXVlY2hpbGVyby5jb20vbGFzNmFt","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"http:\/\/feed.quechilero.com\/las6am","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"https:\/\/www.stitcher.com\/podcast\/pepe-barrascout\/las-6-de-la-maana","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"https:\/\/mx.ivoox.com\/es\/podcast-6-manana_sq_f19907_1.html","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/las-6am","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"7vju9eDF8i\"><a href=\"https:\/\/quechilero.com\/blog\/2013\/02\/13\/podcast-las-6-de-la-manana-episodio-854\/\">Podcast: Las 6 de la ma\u00f1ana, episodio 854<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2013\/02\/13\/podcast-las-6-de-la-manana-episodio-854\/embed\/#?secret=7vju9eDF8i\" width=\"500\" height=\"350\" title=\"\u00abPodcast: Las 6 de la ma\u00f1ana, episodio 854\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"7vju9eDF8i\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/pDKli-6cw","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":23839,"url":"https:\/\/quechilero.com\/blog\/2013\/02\/14\/podcast-las-6-de-la-manana-episodio-855\/","url_meta":{"origin":23840,"position":0},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 855","author":"Pepe Barrascout Ortiz","date":"14 febrero 2013","format":false,"excerpt":"Bienvenidos al octingent\u00e9simo quincuag\u00e9simo quinto episodio de \u201cLas 6 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Stormy Mondays - Every time she smiles 02 - Stormy Mondays\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":26746,"url":"https:\/\/quechilero.com\/blog\/2016\/02\/17\/podcast-las-6am-episodio-1127-the-carpenters\/","url_meta":{"origin":23840,"position":1},"title":"Podcast: Las 6am episodio 1127, The Carpenters","author":"Pepe Barrascout Ortiz","date":"17 febrero 2016","format":false,"excerpt":"Bienvenidos al mil\u00e9simo cent\u00e9simo vig\u00e9simo s\u00e9ptimo\u00a0episodio de \u201cLas 6 de la ma\u00f1ana\u201d, un podcast diario que trae 6 canciones, para que iniciemos el d\u00eda con buena m\u00fasica. Nuestro invitado de hoy: \"The Carpenters\" El listado para hoy es: Artista \/ Tema 01 - Close to you 02 - Rainy Days\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":24372,"url":"https:\/\/quechilero.com\/blog\/2011\/09\/01\/podcast-las-6-de-la-manana-episodio-323\/","url_meta":{"origin":23840,"position":2},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 323","author":"Pepe Barrascout Ortiz","date":"1 septiembre 2011","format":false,"excerpt":"Bienvenidos al tricent\u00e9simo vig\u00e9simo tercer episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Josh Woodward - Together On Our Own 02 - PeerGynt Lobogris -\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":24514,"url":"https:\/\/quechilero.com\/blog\/2011\/04\/12\/podcast-las-6-de-la-manana-episodio-181\/","url_meta":{"origin":23840,"position":3},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 181","author":"Pepe Barrascout Ortiz","date":"12 abril 2011","format":false,"excerpt":"Bienvenidos al cent\u00e9simo octog\u00e9simo primer episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Juanitos - La Black Mustang Foursuite 02 - amelie - soon a\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":23898,"url":"https:\/\/quechilero.com\/blog\/2012\/12\/18\/podcast-las-6-de-la-manana-episodio-797\/","url_meta":{"origin":23840,"position":4},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 797","author":"Pepe Barrascout Ortiz","date":"18 diciembre 2012","format":false,"excerpt":"Bienvenidos al septingent\u00e9simo nonag\u00e9simo s\u00e9ptimo episodio de \u201cLas 6 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - deejoke - summersong 02 - deejoke - sunshine 03 - deejoke\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":24386,"url":"https:\/\/quechilero.com\/blog\/2011\/08\/18\/podcast-las-6-de-la-manana-episodio-309\/","url_meta":{"origin":23840,"position":5},"title":"Podcast: Las 6 de la ma\u00f1ana, episodio 309","author":"Pepe Barrascout Ortiz","date":"18 agosto 2011","format":false,"excerpt":"Bienvenidos al tricent\u00e9simo noveno episodio de\u00a0\u201cLas \u00a06 de la ma\u00f1ana\u201d, un podcast que trae 6 canciones, para que iniciemos el d\u00eda, de forma positiva y con \u00e1nimo. El listado para hoy es: Artista \/ Tema 01 - Josh Woodward - Sugar On My Tongue 02 - echovolt - No Hay\u2026","rel":"","context":"En \u00abLas 6 de la ma\u00f1ana\u00bb","block_context":{"text":"Las 6 de la ma\u00f1ana","link":"https:\/\/quechilero.com\/blog\/category\/podcast\/las-6-de-la-manana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/las6am.jpg?fit=620%2C350&ssl=1","_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/23840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=23840"}],"version-history":[{"count":1,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/23840\/revisions"}],"predecessor-version":[{"id":30312,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/23840\/revisions\/30312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media\/22662"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=23840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=23840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=23840"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=23840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}