{"id":18004,"date":"2014-07-23T08:00:18","date_gmt":"2014-07-23T14:00:18","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=18004"},"modified":"2014-07-22T19:47:37","modified_gmt":"2014-07-23T01:47:37","slug":"que-tan-rapido-vuela-un-avion-de-combate","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2014\/07\/23\/que-tan-rapido-vuela-un-avion-de-combate\/","title":{"rendered":"\u00bfQu\u00e9 tan r\u00e1pido vuela un avi\u00f3n de combate?"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/i0.wp.com\/img.youtube.com\/vi\/xpQgDuyaAHw\/hqdefault.jpg?resize=480%2C360\" alt=\"\" width=\"480\" height=\"360\" \/><\/p>\n<p>En una presentaci\u00f3n de los\u00a0<em>Blue Angels\u00a0<\/em> en San Luis,\u00a0Missouri. Un espectador aficionado, estaba grabando algunas de las maniobras, que a lo lejos hac\u00edan estos aviadores, en especial la ca\u00edda libre de varios aviones, cuando de repente se llev\u00f3 una gran sorpresa.<\/p>\n<p>Impresionante la velocidad que pueden llegar a desarrollar estos aviones y como visualmente pareciera que vuelan muy cerca de nosotros. Recuerdo cuando hace unos a\u00f1os, vinieron a Guatemala e hicieron varias presentaciones. Tuve la oportunidad de ver algunas de las pr\u00e1cticas y es muy impresionante, cuando pareciera que de en medio de los edificios, surgieran estos aviones.<\/p>\n<p>Este video no tiene ning\u00fan desperdicio.<\/p>\n<p><iframe loading=\"lazy\" title=\"Wait for it...\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/xpQgDuyaAHw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una presentaci\u00f3n de los\u00a0Blue Angels\u00a0 en San Luis,\u00a0Missouri. Un espectador aficionado, estaba grabando algunas de las maniobras, que a lo lejos hac\u00edan estos aviadores, en especial la ca\u00edda libre de varios aviones, cuando de repente se llev\u00f3 una gran sorpresa. Impresionante la velocidad que pueden llegar a desarrollar estos aviones y como visualmente pareciera &#8230; <a title=\"\u00bfQu\u00e9 tan r\u00e1pido vuela un avi\u00f3n de combate?\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2014\/07\/23\/que-tan-rapido-vuela-un-avion-de-combate\/\" aria-label=\"Leer m\u00e1s sobre \u00bfQu\u00e9 tan r\u00e1pido vuela un avi\u00f3n de combate?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[113],"tags":[32,10,25,53],"series":[],"class_list":["post-18004","post","type-post","status-publish","format-standard","hentry","category-videoblog","tag-especial","tag-guatemala","tag-video","tag-youtube"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"wbtMrssyiF\"><a href=\"https:\/\/quechilero.com\/blog\/2014\/07\/23\/que-tan-rapido-vuela-un-avion-de-combate\/\">\u00bfQu\u00e9 tan r\u00e1pido vuela un avi\u00f3n de combate?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2014\/07\/23\/que-tan-rapido-vuela-un-avion-de-combate\/embed\/#?secret=wbtMrssyiF\" width=\"500\" height=\"350\" title=\"\u00ab\u00bfQu\u00e9 tan r\u00e1pido vuela un avi\u00f3n de combate?\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"wbtMrssyiF\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-4Go","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/18004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=18004"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/18004\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=18004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=18004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=18004"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=18004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}