{"id":14621,"date":"2012-10-05T08:00:45","date_gmt":"2012-10-05T14:00:45","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=14621"},"modified":"2012-10-05T08:00:45","modified_gmt":"2012-10-05T14:00:45","slug":"los-maestros-mas-importantes","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2012\/10\/05\/los-maestros-mas-importantes\/","title":{"rendered":"Los maestros m\u00e1s importantes"},"content":{"rendered":"<p>Nos encontr\u00e1bamos en la clase de cuarto grado de la se\u00f1orita Tacy, repasando las tablas de multiplicaci\u00f3n, cuando levant\u00e9 la vista y vi que mi padre entraba al sal\u00f3n de clase.<\/p>\n<p>\u00abSe\u00f1orita Tacy,\u00bb escuch\u00e9 a mi padre decir, \u00abpienso salir de viaje ma\u00f1ana, y me voy a llevar a John conmigo algunos d\u00edas para ense\u00f1arle.\u00bb No pod\u00eda creerlo. \u00a1Iba a faltar a la escuela y pasar tiempo junto a mi pap\u00e1! Por poco brinco sobre mi silla.<\/p>\n<p>Pap\u00e1 continu\u00f3 diciendo: \u00abUsted ha hecho un excelente trabajo ense\u00f1ando a John, pero ahora es mi turno por una temporada.\u00bb Entonces se volvi\u00f3 hacia m\u00ed y dijo: \u00abTe ver\u00e9 en casa esta noche, John.\u00bb<\/p>\n<p>Lo que m\u00e1s recuerdo de ese viaje en el Ford Fairlane de mi pap\u00e1 fueron las horas que pasamos hablando de todo: b\u00e9isbol, baloncesto, eventos y noticias, m\u00fasica, la iglesia, la escuela y sobre mis amigos. Era la primera vez que tuve a mi padre para m\u00ed solo.<br \/>\nAquel viaje con mi padre a la edad de diez a\u00f1os me hizo sentir muy importante y mayor. Tambi\u00e9n estableci\u00f3 la manera en que tomar\u00eda el control de mi educaci\u00f3n. \u00c9l y mi madre reconoc\u00edan que ellos eran mis maestros m\u00e1s importantes. Ellos valoraban la ense\u00f1anza que estaba recibiendo en la escuela, pero sab\u00edan que hab\u00eda una diferencia entre la educaci\u00f3n escolar (la adquisici\u00f3n de conocimientos) y el aprendizaje de la vida (el desarrollo de la sabidur\u00eda).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos encontr\u00e1bamos en la clase de cuarto grado de la se\u00f1orita Tacy, repasando las tablas de multiplicaci\u00f3n, cuando levant\u00e9 la vista y vi que mi padre entraba al sal\u00f3n de clase. \u00abSe\u00f1orita Tacy,\u00bb escuch\u00e9 a mi padre decir, \u00abpienso salir de viaje ma\u00f1ana, y me voy a llevar a John conmigo algunos d\u00edas para ense\u00f1arle.\u00bb &#8230; <a title=\"Los maestros m\u00e1s importantes\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2012\/10\/05\/los-maestros-mas-importantes\/\" aria-label=\"Leer m\u00e1s sobre Los maestros m\u00e1s importantes\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[11,39,5,36,24],"series":[],"class_list":["post-14621","post","type-post","status-publish","format-standard","hentry","category-limones","tag-amigo","tag-madre","tag-tiempo","tag-trabajo","tag-vida"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"Yv1VQ82jFt\"><a href=\"https:\/\/quechilero.com\/blog\/2012\/10\/05\/los-maestros-mas-importantes\/\">Los maestros m\u00e1s importantes<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2012\/10\/05\/los-maestros-mas-importantes\/embed\/#?secret=Yv1VQ82jFt\" width=\"500\" height=\"350\" title=\"\u00abLos maestros m\u00e1s importantes\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"Yv1VQ82jFt\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-3NP","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/14621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=14621"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/14621\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=14621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=14621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=14621"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=14621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}