{"id":13923,"date":"2012-10-14T08:00:08","date_gmt":"2012-10-14T14:00:08","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=13923"},"modified":"2012-10-14T08:00:08","modified_gmt":"2012-10-14T14:00:08","slug":"el-amor-es-un-pajaro-rebelde","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2012\/10\/14\/el-amor-es-un-pajaro-rebelde\/","title":{"rendered":"El amor es un p\u00e1jaro rebelde"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Carmen Monarcha &amp; Andre Rieu - Habanera 2010\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/2PIj2wMUAqI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>L&#8217;amour est un oiseau rebelle<\/strong> <em>(El amor es un p\u00e1jaro rebelde)<\/em>, aria (habanera) para mezzosoprano del primer acto la <em>\u00f3pera Carmen<\/em> de <em>Georges Bizet<\/em>, compuesta en 1875 y basada en una habanera de Sebasti\u00e1n Iradier, titulada El Arreglito, si bien Bizet pensaba que la melod\u00eda era de origen popular.<\/p>\n<p>Esta versi\u00f3n es interpretada por\u00a0<em>Carmen Monarcha<\/em> con la orquesta de c\u00e1mara dirigida por <em>Andre Rieu<\/em>.<\/p>\n<p>[izquierda]L&#8217;amour est un oiseau rebelle<br \/>\nque nul ne peut apprivoiser,<br \/>\net c&#8217;est bien en vain qu&#8217;on l&#8217;appelle,<br \/>\ns&#8217;il lui convient de refuser.<br \/>\nRien n&#8217;y fait, menace ou pri\u00e8re,<br \/>\nl&#8217;un parle bien, l&#8217;autre se tait:<br \/>\nEt c&#8217;est l&#8217;autre que je pr\u00e9f\u00e8re,<br \/>\nIl n&#8217;a rien dit mais il me pla\u00eet.<br \/>\nL&#8217;amour ! l&#8217;amour ! l&#8217;amour ! l&#8217;amour !<\/p>\n<p>L&#8217;amour est enfant de boh\u00e8me,<br \/>\nil n&#8217;a jamais, jamais connu de loi;<br \/>\nsi tu ne m&#8217;aimes pas, je t&#8217;aime:<br \/>\nsi je t&#8217;aime, prends garde \u00e0 toi !<br \/>\nL\u00b4mour !<\/p>\n<p>L&#8217;oiseau que tu croyais surprendre<br \/>\nbattit de l&#8217;aile et s&#8217;envola &#8230;<br \/>\nl&#8217;amour est loin, tu peux l&#8217;attendre;<br \/>\ntu ne l&#8217;attends plus, il est l\u00e0!<br \/>\nTout autour de toi, vite, vite,<br \/>\nil vient, s&#8217;en va, puis il revient &#8230;<br \/>\ntu crois le tenir, il t&#8217;\u00e9vite,<br \/>\ntu crois l&#8217;\u00e9viter, il te tient.<br \/>\nL&#8217;amour! l&#8217;amour!, l&#8217;amour, l&#8217;amour![\/izquierda]<\/p>\n<p>[derecha]El amor es un p\u00e1jaro rebelde<br \/>\nque nadie puede dominar,<br \/>\ny se le llama bien en vano,<br \/>\nsi \u00e9l prefiere rechazar.<br \/>\nNada ayuda, amenaza u oraci\u00f3n,<br \/>\nuno habla, otro se calla:<br \/>\nY es al otro al que prefiero,<br \/>\nno ha dicho nada pero me gusta.<br \/>\n\u00a1El amor! \u00a1el amor! \u00a1el amor! \u00a1el amor!<\/p>\n<p>El amor es hijo de gitano,<br \/>\njam\u00e1s, jam\u00e1s ha conocido ley;<br \/>\nsi no me amas, yo te amo:<br \/>\nsi te amo, \u00a1t\u00fa ten cuidado!.<\/p>\n<p>El ave a la que crees sorprender<br \/>\nbati\u00f3 el ala y vol\u00f3 &#8230;<br \/>\nel amor est\u00e1 lejos, puedes esperar;<br \/>\n\u00a1ya no lo esperas y ah\u00ed est\u00e1!!<br \/>\nAlrededor de ti, r\u00e1pido, r\u00e1pido,<br \/>\nvino, se va, vuelve a venir &#8230;<br \/>\ncrees tenerlo, te evita,<br \/>\ncrees evitarlo, te tiene.<br \/>\n\u00a1El amor! \u00a1el amor! \u00a1el amor! \u00a1el amor![\/derecha]<\/p>\n<p><em>Feliz Cumplea\u00f1os Kiki.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;amour est un oiseau rebelle (El amor es un p\u00e1jaro rebelde), aria (habanera) para mezzosoprano del primer acto la \u00f3pera Carmen de Georges Bizet, compuesta en 1875 y basada en una habanera de Sebasti\u00e1n Iradier, titulada El Arreglito, si bien Bizet pensaba que la melod\u00eda era de origen popular. Esta versi\u00f3n es interpretada por\u00a0Carmen Monarcha &#8230; <a title=\"El amor es un p\u00e1jaro rebelde\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2012\/10\/14\/el-amor-es-un-pajaro-rebelde\/\" aria-label=\"Leer m\u00e1s sobre El amor es un p\u00e1jaro rebelde\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[15,37,46,54,86,53],"series":[],"class_list":["post-13923","post","type-post","status-publish","format-standard","hentry","category-limones","tag-amor","tag-ayuda","tag-feliz","tag-kiki","tag-oracion","tag-youtube"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"V4tLjXG9AZ\"><a href=\"https:\/\/quechilero.com\/blog\/2012\/10\/14\/el-amor-es-un-pajaro-rebelde\/\">El amor es un p\u00e1jaro rebelde<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2012\/10\/14\/el-amor-es-un-pajaro-rebelde\/embed\/#?secret=V4tLjXG9AZ\" width=\"500\" height=\"350\" title=\"\u00abEl amor es un p\u00e1jaro rebelde\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"V4tLjXG9AZ\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-3Cz","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/13923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=13923"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/13923\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=13923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=13923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=13923"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=13923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}