{"id":13341,"date":"2012-05-14T08:00:02","date_gmt":"2012-05-14T14:00:02","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=13341"},"modified":"2012-05-14T08:00:02","modified_gmt":"2012-05-14T14:00:02","slug":"me-enganaron","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2012\/05\/14\/me-enganaron\/","title":{"rendered":"Me enga\u00f1aron"},"content":{"rendered":"<p>Anochec\u00eda. Mi esposa y yo acab\u00e1bamos de caminar por el famoso puente Charles en Praga cuando un hombre se nos acerc\u00f3 con un fajo de dinero en la mano. <em>\u00abCuarenta y dos coronas checas por un d\u00f3lar\u00bb<\/em> -dijo. La tasa oficial era de unas 35 coronas por un d\u00f3lar estadounidense. As\u00ed que cambi\u00e9 $50 por 2,100 coronas checas.<\/p>\n<p>Esa noche le habl\u00e9 a mi hijo de mi buena fortuna. <em>\u00abPap\u00e1, deb\u00ed hab\u00e9rtelo dicho<\/em> -dijo disculp\u00e1ndose- . <em>Nunca cambies dinero en la calle.\u00bb<\/em> Miramos los billetes. El de 100 coronas era aut\u00e9ntico, pero los dos de 1,000 coronas no val\u00edan nada. Parec\u00edan dinero checo, pero eran billetes b\u00falgaros que ya no estaban en circulaci\u00f3n. Me hab\u00edan enga\u00f1ado y me hab\u00edan robado.<\/p>\n<p>Satan\u00e1s emplea t\u00e1cticas similares (Juan 8:44). Se aprovecha del enga\u00f1o del pecado usando sus <em>\u00abplaceres temporales\u00bb<\/em> (Hebreos 11:25) para ocultar el dolor que siempre viene despu\u00e9s. El pecado puede ser atractivo, e incluso ofrecer algo que es bueno en s\u00ed mismo. Pero detr\u00e1s de ello hay enga\u00f1o.<\/p>\n<p>Nuestra mejor defensa contra el enga\u00f1o es tener un conocimiento cada vez mayor de la Palabra de Dios. Si imitamos el ejemplo del salmista nos guardaremos de ser enga\u00f1ados por el pecado:<em> \u00abEn mi coraz\u00f3n he atesorado Tu Palabra, para no pecar contra Ti.\u00bb<\/em> (Salmo 119:11).<\/p>\n<p><em><strong>Dennis De Haan<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anochec\u00eda. Mi esposa y yo acab\u00e1bamos de caminar por el famoso puente Charles en Praga cuando un hombre se nos acerc\u00f3 con un fajo de dinero en la mano. \u00abCuarenta y dos coronas checas por un d\u00f3lar\u00bb -dijo. La tasa oficial era de unas 35 coronas por un d\u00f3lar estadounidense. As\u00ed que cambi\u00e9 $50 por &#8230; <a title=\"Me enga\u00f1aron\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2012\/05\/14\/me-enganaron\/\" aria-label=\"Leer m\u00e1s sobre Me enga\u00f1aron\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[26,51,18,42],"series":[],"class_list":["post-13341","post","type-post","status-publish","format-standard","hentry","category-limones","tag-dinero","tag-dios","tag-hombre","tag-palabra"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"v0i9gEL8fa\"><a href=\"https:\/\/quechilero.com\/blog\/2012\/05\/14\/me-enganaron\/\">Me enga\u00f1aron<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2012\/05\/14\/me-enganaron\/embed\/#?secret=v0i9gEL8fa\" width=\"500\" height=\"350\" title=\"\u00abMe enga\u00f1aron\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"v0i9gEL8fa\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-3tb","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/13341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=13341"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/13341\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=13341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=13341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=13341"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=13341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}