{"id":13297,"date":"2012-05-13T08:00:27","date_gmt":"2012-05-13T14:00:27","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=13297"},"modified":"2012-05-13T08:00:27","modified_gmt":"2012-05-13T14:00:27","slug":"timelapse-moscu-%d0%bc%d0%be%d1%81%d0%ba%d0%b2%d0%b0-%d1%80%d0%be%d1%81%d1%81%d0%b8%d1%8f","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2012\/05\/13\/timelapse-moscu-%d0%bc%d0%be%d1%81%d0%ba%d0%b2%d0%b0-%d1%80%d0%be%d1%81%d1%81%d0%b8%d1%8f\/","title":{"rendered":"Timelapse: Mosc\u00fa (\u041c\u043e\u0441\u043a\u0432\u0430 \/ \u0420\u043e\u0441\u0441\u0438\u044f)"},"content":{"rendered":"<!-- vimeo error: not a vimeo video -->\n<p>Este magn\u00edfico video, hecho con la t\u00e9cnica de <em>Timelapse<\/em>, muestra la enigm\u00e1tica ciudad de Mosc\u00fa y sus principales detalles arquitect\u00f3nicos. Toda la belleza y el arte de la capital de Rusia, ha sido resumido en un poco mas de dos minutos.<\/p>\n<p>Para este video se utiliz\u00f3 el siguiente equipo:<\/p>\n<p>Canon 5D Mark II<br \/>\nCanon 60D<br \/>\ntokina 11-16mm\/2.8<br \/>\nsigma 24mm\/1.8<br \/>\ncanon 50mm\/1.4<br \/>\ncanon 70-200mm\/4lis<br \/>\nNDx16, NDx1000, NDx2000, c-pl<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este magn\u00edfico video, hecho con la t\u00e9cnica de Timelapse, muestra la enigm\u00e1tica ciudad de Mosc\u00fa y sus principales detalles arquitect\u00f3nicos. Toda la belleza y el arte de la capital de Rusia, ha sido resumido en un poco mas de dos minutos. Para este video se utiliz\u00f3 el siguiente equipo: Canon 5D Mark II Canon 60D &#8230; <a title=\"Timelapse: Mosc\u00fa (\u041c\u043e\u0441\u043a\u0432\u0430 \/ \u0420\u043e\u0441\u0441\u0438\u044f)\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2012\/05\/13\/timelapse-moscu-%d0%bc%d0%be%d1%81%d0%ba%d0%b2%d0%b0-%d1%80%d0%be%d1%81%d1%81%d0%b8%d1%8f\/\" aria-label=\"Leer m\u00e1s sobre Timelapse: Mosc\u00fa (\u041c\u043e\u0441\u043a\u0432\u0430 \/ \u0420\u043e\u0441\u0441\u0438\u044f)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[16,25],"series":[],"class_list":["post-13297","post","type-post","status-publish","format-standard","hentry","category-limones","tag-equipo","tag-video"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"euhooTyZNw\"><a href=\"https:\/\/quechilero.com\/blog\/2012\/05\/13\/timelapse-moscu-%d0%bc%d0%be%d1%81%d0%ba%d0%b2%d0%b0-%d1%80%d0%be%d1%81%d1%81%d0%b8%d1%8f\/\">Timelapse: Mosc\u00fa (\u041c\u043e\u0441\u043a\u0432\u0430 \/ \u0420\u043e\u0441\u0441\u0438\u044f)<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2012\/05\/13\/timelapse-moscu-%d0%bc%d0%be%d1%81%d0%ba%d0%b2%d0%b0-%d1%80%d0%be%d1%81%d1%81%d0%b8%d1%8f\/embed\/#?secret=euhooTyZNw\" width=\"500\" height=\"350\" title=\"\u00abTimelapse: Mosc\u00fa (\u041c\u043e\u0441\u043a\u0432\u0430 \/ \u0420\u043e\u0441\u0441\u0438\u044f)\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"euhooTyZNw\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-3st","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/13297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=13297"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/13297\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=13297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=13297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=13297"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=13297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}