{"id":13289,"date":"2012-05-12T08:00:50","date_gmt":"2012-05-12T14:00:50","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=13289"},"modified":"2012-05-12T08:00:50","modified_gmt":"2012-05-12T14:00:50","slug":"jorge-maravilha-chico-buarque","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2012\/05\/12\/jorge-maravilha-chico-buarque\/","title":{"rendered":"Jorge Maravilha &#8211; Chico Buarque"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"PLAYMOBILLE - Jorge Maravilha - trilha Malha\u00e7\u00e3o ID\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/tYWkweKw5ME?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>LETRA: Jorge Maravilha<br \/>\n(Leonel Paiva, Chico Buarque)<\/p>\n<p>E nada como um tempo ap\u00f3s um contratempo<br \/>\nPro meu cora\u00e7\u00e3o<br \/>\nE n\u00e3o vale a pena ficar, apenas ficar<br \/>\nChorando, resmungando, at\u00e9 quando? N\u00e3o, n\u00e3o&#8230;<br \/>\nE como j\u00e1 dizia Jorge Maravilha<br \/>\nPrenhe de raz\u00e3o<br \/>\nMais vale uma filha na m\u00e3o<br \/>\nDo que dois pais sobrevoando<\/p>\n<p>Voc\u00ea n\u00e3o gosta de mim, mas sua filha gosta<br \/>\nVoc\u00ea n\u00e3o gosta de mim, mas sua filha gosta &#8211; Eu vou fazer o qu\u00ea?<br \/>\nEla gosta do tango, do dengo, do mengo, domingo e de cosca<br \/>\nEla pega e me pisca, belisca, petisca, me arrisca e me enrosca<\/p>\n<p>E nada como um dia ap\u00f3s o outro dia<br \/>\nPro meu cora\u00e7\u00e3o<br \/>\nE n\u00e3o vale a pena ficar, apenas ficar<br \/>\nChorando, resmungando at\u00e9 quando?&#8230;<br \/>\nE como j\u00e1 dizia Jorge Maravilha<br \/>\nPrenhe de raz\u00e3o<br \/>\nMais vale uma filha na m\u00e3o do que dois pais sobrevoando<\/p>\n<p>Voc\u00ea n\u00e3o gosta de mim, mas sua filha gosta<br \/>\nVoc\u00ea n\u00e3o gosta de mim, mas sua filha gosta\u00a0&#8211; Eu vou fazer o qu\u00ea?<br \/>\nEla gosta do tango, do dengo, do mengo, domingo e de cosca<br \/>\nEla pega e me pisca, belisca, petisca, me arrisca e me enrosca<\/p>\n<p>E nada como um dia ap\u00f3s o outro dia<br \/>\nPro meu cora\u00e7\u00e3o<br \/>\nE n\u00e3o vale a pena ficar, apenas ficar<br \/>\nChorando, resmungando at\u00e9 quando? N\u00e3o, n\u00e3o&#8230;<br \/>\nE como j\u00e1 dizia Jorge Maravilha<br \/>\nPrenhe de raz\u00e3o<br \/>\nMais vale uma filha na m\u00e3o do que dois pais sobrevoando<\/p>\n<p>Voc\u00ea n\u00e3o gosta de mim, mas sua filha gosta<br \/>\nVoc\u00ea n\u00e3o gosta de mim, mas sua filha gosta\u00a0&#8211; Eu vou fazer o qu\u00ea?<br \/>\nEla gosta do tango, do dengo, do mengo, domingo e de cosca<br \/>\nEla pega e me pisca, petisca, belisca, me arrisca e me enrosca<\/p>\n<p>E como j\u00e1 dizia Jorge Maravilha<br \/>\nPrenhe de raz\u00e3o<br \/>\nMais vale uma filha na m\u00e3o do que dois pais sobrevoando<\/p>\n<p>Voc\u00ea n\u00e3o gosta de mim, mas sua filha gosta<br \/>\nEu j\u00e1 falei pra voc\u00ea&#8230; Mas sua filha insiste em me querer<br \/>\nEla gosta do tango, do dengo, do mengo, domingo e de cosca<br \/>\nEla pega e me pisca, petisca,\u00a0belisca, me arrisca e me enrosca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LETRA: Jorge Maravilha (Leonel Paiva, Chico Buarque) E nada como um tempo ap\u00f3s um contratempo Pro meu cora\u00e7\u00e3o E n\u00e3o vale a pena ficar, apenas ficar Chorando, resmungando, at\u00e9 quando? N\u00e3o, n\u00e3o&#8230; E como j\u00e1 dizia Jorge Maravilha Prenhe de raz\u00e3o Mais vale uma filha na m\u00e3o Do que dois pais sobrevoando Voc\u00ea n\u00e3o gosta &#8230; <a title=\"Jorge Maravilha &#8211; Chico Buarque\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2012\/05\/12\/jorge-maravilha-chico-buarque\/\" aria-label=\"Leer m\u00e1s sobre Jorge Maravilha &#8211; Chico Buarque\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[57,53],"series":[],"class_list":["post-13289","post","type-post","status-publish","format-standard","hentry","category-limones","tag-voce","tag-youtube"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"DtUNBVgWp9\"><a href=\"https:\/\/quechilero.com\/blog\/2012\/05\/12\/jorge-maravilha-chico-buarque\/\">Jorge Maravilha &#8211; Chico Buarque<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2012\/05\/12\/jorge-maravilha-chico-buarque\/embed\/#?secret=DtUNBVgWp9\" width=\"500\" height=\"350\" title=\"\u00abJorge Maravilha &#8211; Chico Buarque\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"DtUNBVgWp9\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-3sl","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/13289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=13289"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/13289\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=13289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=13289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=13289"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=13289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}