{"id":12965,"date":"2012-03-22T08:00:18","date_gmt":"2012-03-22T14:00:18","guid":{"rendered":"http:\/\/quechilero.com\/blog\/?p=12965"},"modified":"2012-03-22T08:00:18","modified_gmt":"2012-03-22T14:00:18","slug":"juego-de-ninos","status":"publish","type":"post","link":"https:\/\/quechilero.com\/blog\/2012\/03\/22\/juego-de-ninos\/","title":{"rendered":"Juego de ni\u00f1os"},"content":{"rendered":"<p>Despu\u00e9s que una tormenta sorpresa cubriera de nieve el Medio Oriente, una foto del peri\u00f3dico mostr\u00f3 a cuatro hombres armados sonriendo mientras constru\u00edan un mu\u00f1eco de nieve fuera de las maltrechas murallas de un cuartel general militar.<\/p>\n<p>El clima invernal tambi\u00e9n hizo que se cancelara una protesta y se retrasara un debate sobre asuntos parlamentarios de mucha importancia. Se vieron jugando en la nieve hombres con t\u00fanicas largas y mujeres con vestidos negros tradicionales y pa\u00f1uelos en la cabeza. Hay algo en la nieve que saca el ni\u00f1o que hay en todos nosotros.<\/p>\n<p>Y hay algo en el evangelio que nos llama a abandonar nuestras profundas hostilidades y sentimientos de importancia propia en favor de una humildad y una fe infantiles. Cuando a Jes\u00fas le preguntaron: <em>\u00ab\u00bfQui\u00e9n es, entonces, el mayor en el reino de los cielos?\u00bb<\/em> (Mateo 18:1), llam\u00f3 a un ni\u00f1o peque\u00f1o para que se le acercara y dijo:<em> \u00abSi no os convert\u00eds y os hac\u00e9is como ni\u00f1os, no entrar\u00e9is en el reino de los cielos\u00bb<\/em> (v.3).<\/p>\n<p>Se ha dicho que la edad disminuye nuestra imaginaci\u00f3n, esperanzas y posibilidades. Mientras m\u00e1s envejecemos, m\u00e1s f\u00e1cilmente decimos: \u00abEso nunca podr\u00eda suceder.\u00bb Pero en la mente de un ni\u00f1o, Dios puede hacer cualquier cosa. Una fe infantil maravillada y con confianza en Dios abre la puerta del reino de los cielos.<\/p>\n<p>La fe brilla m\u00e1s en un coraz\u00f3n que es como el de un ni\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s que una tormenta sorpresa cubriera de nieve el Medio Oriente, una foto del peri\u00f3dico mostr\u00f3 a cuatro hombres armados sonriendo mientras constru\u00edan un mu\u00f1eco de nieve fuera de las maltrechas murallas de un cuartel general militar. El clima invernal tambi\u00e9n hizo que se cancelara una protesta y se retrasara un debate sobre asuntos parlamentarios &#8230; <a title=\"Juego de ni\u00f1os\" class=\"read-more\" href=\"https:\/\/quechilero.com\/blog\/2012\/03\/22\/juego-de-ninos\/\" aria-label=\"Leer m\u00e1s sobre Juego de ni\u00f1os\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[38,51,90,18,74,20,82],"series":[],"class_list":["post-12965","post","type-post","status-publish","format-standard","hentry","category-limones","tag-confianza","tag-dios","tag-evangelio","tag-hombre","tag-jesus","tag-mujer","tag-sentimiento"],"episode_featured_image":false,"episode_player_image":"https:\/\/i0.wp.com\/quechilero.com\/blog\/imagenes\/podcast.png?fit=1831%2C1831&ssl=1","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"castbox":{"key":"castbox","url":"","label":"CastBox","class":"castbox","icon":"castbox.png"},"deezer":{"key":"deezer","url":"","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"listen_notes":{"key":"listen_notes","url":"","label":"Listen Notes","class":"listen_notes","icon":"listen-notes.png"},"pandora":{"key":"pandora","url":"","label":"Pandora","class":"pandora","icon":"pandora.png"},"podbean":{"key":"podbean","url":"","label":"Podbean","class":"podbean","icon":"podbean.png"},"podcast_republic":{"key":"podcast_republic","url":"","label":"Podcast Republic","class":"podcast_republic","icon":"podcast-republic.png"},"rss":{"key":"rss","url":"","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"tunein":{"key":"tunein","url":"","label":"TuneIn","class":"tunein","icon":"tunein.png"},"youtube":{"key":"youtube","url":"","label":"YouTube","class":"youtube","icon":"youtube.png"},"iheartradio":{"key":"iheartradio","url":"","label":"iHeartRadio","class":"iheartradio","icon":"iheartradio.png"},"ivoox":{"key":"ivoox","url":"","label":"iVoox","class":"ivoox","icon":"ivoox.png"}},"rssFeedUrl":"https:\/\/quechilero.com\/blog\/feed\/podcast\/si-la-vida-nos-da-limones","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"Uhw2mjxmZG\"><a href=\"https:\/\/quechilero.com\/blog\/2012\/03\/22\/juego-de-ninos\/\">Juego de ni\u00f1os<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/quechilero.com\/blog\/2012\/03\/22\/juego-de-ninos\/embed\/#?secret=Uhw2mjxmZG\" width=\"500\" height=\"350\" title=\"\u00abJuego de ni\u00f1os\u00bb \u2014 Si la Vida nos da Limones...\" data-secret=\"Uhw2mjxmZG\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/quechilero.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pDKli-3n7","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/12965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/comments?post=12965"}],"version-history":[{"count":0,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/posts\/12965\/revisions"}],"wp:attachment":[{"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/media?parent=12965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/categories?post=12965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/tags?post=12965"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/quechilero.com\/blog\/wp-json\/wp\/v2\/series?post=12965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}